{"id":2365,"date":"2024-05-24T14:26:51","date_gmt":"2024-05-24T12:26:51","guid":{"rendered":"https:\/\/ragt-seeds.com\/es\/?page_id=2365"},"modified":"2024-11-22T08:42:25","modified_gmt":"2024-11-22T07:42:25","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/ragt-seeds.com\/es\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2365\" class=\"elementor elementor-2365\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7852c1 e-flex e-con-boxed e-con e-parent\" data-id=\"d7852c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#273540\" class=\"elementor-element elementor-element-bfc3878 elementor-widget elementor-widget-heading\" data-id=\"bfc3878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aviso Legal<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b733ed elementor-widget elementor-widget-text-editor\" data-id=\"4b733ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Aviso legal y condiciones de uso<\/h3><p>Bienvenido a este sitio dedicado a la informaci\u00f3n sobre RAGT SEMENCES (en adelante, el \u00abSitio\u00bb). Le invitamos a leer atentamente las presentes condiciones de uso que rigen la navegaci\u00f3n en este Sitio (en adelante, las \u00abCondiciones de Uso\u00bb). Al utilizar el Sitio, acepta sin reservas las presentes Condiciones de Uso.<\/p><p>Si tiene alguna duda sobre el uso del Sitio, p\u00f3ngase en contacto con nosotros en la siguiente direcci\u00f3n: <a href=\"mailto:contactos@ragt.es\">contactos@ragt.es<\/a>.<\/p><h3>Avisos legales<\/h3><p><strong>URL del sitio :<\/strong> www.ragt.es<\/p><p><strong>Contacto :<\/strong><br \/>Correo electr\u00f3nico : <a href=\"mailto:contactos@ragt.es\">contactos@ragt.es<\/a><br \/>Tel\u00e9fono : +335 65 73 41 00 &#8211; Fax : +335 65 73 41 99<\/p><p><strong>Director de la publicaci\u00f3n :<\/strong> D. Damien ROBERT<\/p><p>Editor : RAGT SEMENCES S.A.S con un capital de 43.275.010 euros, con domicilio social<br \/>en site de Bourran, rue Emile Singla, 12000 RODEZ, inscrita en el Registro Mercantil de Rodez con el n\u00famero 431 899 756. N\u00famero de IVA: FR 52 431 899 756.<\/p><p><strong>Alojado en :<\/strong> Cibleweb.com<br \/>1 rue Lignon, 34500 B\u00e9ziers, Francia<br \/><strong>P\u00e1gina web : <\/strong><a href=\"https:\/\/www.cibleweb.com\/\" rel=\"nofollow noopener\" target=\"_blank\">www.cibleweb.com<\/a><\/p><p><strong>Dise\u00f1o y realizaci\u00f3n :<\/strong> AGENCE CANTOU<br \/>Parc Commercial Saint-Marc 12850 Onet-le-Ch\u00e2teau, Francia<br \/><strong>P\u00e1gina web :<\/strong> <a href=\"https:\/\/agencecantou.fr\/\" rel=\"nofollow noopener\" target=\"_blank\">agencecantou.fr<\/a><\/p><h3>1. Acceso al sitio<\/h3><p>Puede acceder al Sitio de forma libre y gratuita, sin registrarse ni crear una cuenta. El acceso al Sitio y\/o a algunas de sus secciones puede requerir el uso de c\u00f3digos de acceso personales. En este caso, le corresponde a usted tomar las medidas adecuadas para garantizar la confidencialidad de dichos c\u00f3digos. Por supuesto, puede cambiarlos en cualquier momento. No obstante, el n\u00famero de intentos de acceso al Sitio y\/o a algunas de sus secciones puede estar limitado para evitar el uso fraudulento de estos c\u00f3digos. Le rogamos que nos informe de cualquier uso fraudulento del que tenga conocimiento. Adem\u00e1s, en caso de incumplimiento de las normas descritas en las presentes condiciones de uso, nos reservamos el derecho de suspender su acceso. No obstante, usted seguir\u00e1 siendo responsable de los costes de acceso y utilizaci\u00f3n de la red de telecomunicaciones.<\/p><h3>2. Propiedad intelectual<\/h3><p>La P\u00e1gina y todos los elementos que la componen (tales como marcas comerciales, textos, videos, etc) est\u00e1n protegidos por la ley de propiedad intelectual. Queda prohibido cualquier uso, reproducci\u00f3n o representaci\u00f3n del la P\u00e1gina para otras finalidades, ya sea de forma total o parcial, e independientemente de la v\u00eda. Estos t\u00e9rminos de uso no implican ning\u00fan tipo de cesi\u00f3n de los derechos de propiedad intelectual aplicables a los elementos de RAGT IBERICA para disfrute de quien los use. Ponemos a tu disposici\u00f3n en la P\u00e1gina contenido que tienes autorizaci\u00f3n para descargar (en adelante el \u00abContenido descargable\u00bb). Te otorgamos los derechos de uso del Contenido descargable de manera intransferible sin exclusividad, gratuita y en los t\u00e9rminos legales definidos por la legislaci\u00f3n de la protecci\u00f3n de la propiedad intelectual; \u00fanicamente para tu uso personal y privado. Queda prohibida cualquier reproducci\u00f3n, representaci\u00f3n, modificaci\u00f3n o distribuci\u00f3n del Contenido descargable.<\/p><h3>3. Enlaces hipertexto<\/h3><p>RAGT SEMENCES se reserva el derecho de establecer y suprimir en su sitio web enlaces que den acceso a p\u00e1ginas web distintas de las de su Sitio. Se le informa de que los sitios a los que puede acceder a trav\u00e9s de los enlaces no pertenecen a RAGT SEMENCES. RAGT SEMENCES declina toda responsabilidad en cuanto al contenido de la informaci\u00f3n proporcionada en estos sitios cuando se activa el enlace. Queda prohibida la creaci\u00f3n de un enlace a este sitio web sin la autorizaci\u00f3n previa y expresa de RAGT SEMENCES. RAGT SEMENCES no se hace responsable del acceso por parte de los usuarios a los enlaces del Sitio a otros recursos de Internet.<\/p><h3>4. Datos personales y cookies<\/h3><p>Podemos recopilar datos personales sobre usted, en particular, cuando se autentifica, descarga Contenidos Descargables o nos env\u00eda un correo electr\u00f3nico. Las cookies son archivos que se depositan en su dispositivo cuando navega por el Sitio (como las p\u00e1ginas que ha visitado, la fecha y hora de su visita, etc.) y que pueden leerse cuando vuelva a visitar el Sitio. Para m\u00e1s informaci\u00f3n sobre el tratamiento de sus datos personales y el uso de cookies, consulte nuestra Pol\u00edtica de Protecci\u00f3n de Datos Personales, a la que puede acceder <a href=\"https:\/\/ragt-seeds.com\/es\/personal-data-protection-policypolitica-de-proteccion-de-datos-personales\/\">aqu\u00ed<\/a>.<\/p><h3>5. Modificaci\u00f3n del sitio y de las condiciones de uso<\/h3><p>Podemos modificar el contenido y la informaci\u00f3n incluidos en este Sitio, as\u00ed como las presentes Condiciones de Uso, en particular para cumplir con cualquier nueva legislaci\u00f3n y\/o normativa aplicable y\/o para mejorar el Sitio. Por lo tanto, le invitamos a que, la pr\u00f3xima vez que visite el Sitio, vuelva a leer estas condiciones y tome nota de los cambios que se hayan podido realizar. El uso continuo del Sitio implica su aceptaci\u00f3n de las nuevas Condiciones de Uso.<\/p><h3>6. Responsabilidad del editor<\/h3><p>Nos esforzamos por mantener el Sitio y los Contenidos Descargables accesibles en todo momento. Sin embargo, no podemos garantizar que el Sitio est\u00e9 disponible y accesible en todo momento. Podemos vernos obligados a suspender temporalmente el acceso parcial o total al Sitio, en particular por razones de mantenimiento t\u00e9cnico.<\/p><p>Tambi\u00e9n se especifica que la red de Internet y los sistemas inform\u00e1ticos y de telecomunicaciones no est\u00e1n exentos de errores y que pueden producirse interrupciones y aver\u00edas. No podemos ofrecer ninguna garant\u00eda a este respecto y, por lo tanto, no se nos podr\u00e1 considerar responsables de ning\u00fan da\u00f1o inherente a este uso de Internet y de los sistemas inform\u00e1ticos y de telecomunicaciones, incluidos, entre otros, los siguientes:<\/p><ul><li>mala transmisi\u00f3n y\/o recepci\u00f3n de cualquier dato y\/o informaci\u00f3n en Internet;<\/li><li>la intrusi\u00f3n externa o la presencia de un virus inform\u00e1tico<\/li><li>fallo de cualquier equipo de recepci\u00f3n o l\u00edneas de comunicaci\u00f3n<\/li><li>y cualquier otro fallo de funcionamiento de la red de Internet que impida el correcto funcionamiento del Sitio.<\/li><\/ul><p>Por \u00faltimo, s\u00f3lo podremos ser considerados responsables de los da\u00f1os directos, con exclusi\u00f3n de cualquier otro da\u00f1o o perjuicio de cualquier naturaleza.<\/p><h3>7. Responsabilidades del usuario<\/h3><p>Usted se compromete a utilizar los servicios del Sitio y la informaci\u00f3n que contiene \u00fanicamente para fines conformes al orden p\u00fablico, a las normas de comportamiento aceptadas y a los derechos de terceros. Usted reconoce haber comprobado que la configuraci\u00f3n de su ordenador est\u00e1 libre de virus y en perfecto estado de funcionamiento. Se compromete a no interferir en el uso del Sitio por parte de otros usuarios y a no acceder a partes del Sitio cuyo acceso est\u00e9 reservado. Se compromete a no cometer ning\u00fan acto que pueda poner en peligro la seguridad inform\u00e1tica de RAGT SEMENCES o de otros usuarios. Asimismo, se compromete a no interferir ni interrumpir el funcionamiento normal del Sitio. Tambi\u00e9n se compromete a abstenerse de cualquier forma de prospecci\u00f3n comercial, especialmente en forma de correos electr\u00f3nicos no solicitados. No debe recopilar, utilizar ni procesar datos personales de otros usuarios. Los usuarios de este Sitio son enteramente responsables del contenido y la exactitud de la informaci\u00f3n que env\u00eden a RAGT SEMENCES y de respetar los derechos de terceros relativos a dicha informaci\u00f3n.<\/p><p><strong>Si visita este Sitio o descarga su contenido desde un lugar distinto de Francia, tenga en cuenta que es su responsabilidad comprobar que act\u00faa de conformidad con la legislaci\u00f3n aplicable en dicho lugar.<\/strong><\/p><h3>8. Legislaci\u00f3n aplicable y litigios<\/h3><p>Las Condiciones de Uso se rigen por la legislaci\u00f3n francesa. Esto se aplica tanto a las normas de fondo como a las formales. Cualquier litigio derivado de la aplicaci\u00f3n de las presentes condiciones de uso ser\u00e1 competencia de los tribunales del domicilio social de RAGT SEMENCES.<\/p><p>Se precisa que en caso de impugnaci\u00f3n de la legalidad de las presentes condiciones de uso, los avisos legales no se ver\u00e1n afectados, ya que constituyen un acto de pleno derecho, independiente de las condiciones de uso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aviso legal y condiciones de uso Bienvenido a este sitio dedicado a la informaci\u00f3n sobre RAGT SEMENCES (en adelante, el \u00abSitio\u00bb). Le invitamos a leer atentamente las presentes condiciones de uso que rigen la navegaci\u00f3n en este Sitio (en adelante, las \u00abCondiciones de Uso\u00bb). Al utilizar el Sitio, acepta sin reservas las presentes Condiciones de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","iawp_total_views":96,"footnotes":""},"class_list":["post-2365","page","type-page","status-publish","hentry","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/pages\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":34,"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/pages\/2365\/revisions"}],"predecessor-version":[{"id":6121,"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/pages\/2365\/revisions\/6121"}],"wp:attachment":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/media?parent=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}