{"id":101,"count":9,"description":"","link":"https:\/\/ragt-seeds.com\/es\/categoria-productos\/proteaginosas\/","name":"Proteaginosas","slug":"proteaginosas","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/product_cat\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/ragt-seeds.com\/es\/wp-json\/wp\/v2\/product?product_cat=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}