{"id":462,"count":1,"description":"","link":"https:\/\/ragt-seeds.com\/uk\/product-category\/triticale\/protien-triticale\/","name":"Protein +","slug":"protien-triticale","taxonomy":"product_cat","parent":461,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/ragt-seeds.com\/uk\/wp-json\/wp\/v2\/product_cat\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ragt-seeds.com\/uk\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ragt-seeds.com\/uk\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ragt-seeds.com\/uk\/wp-json\/wp\/v2\/product_cat\/461"}],"wp:post_type":[{"href":"https:\/\/ragt-seeds.com\/uk\/wp-json\/wp\/v2\/product?product_cat=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}